{"id":30236,"date":"2025-10-22T15:44:56","date_gmt":"2025-10-22T18:44:56","guid":{"rendered":"https:\/\/embrevenoar.com.br\/dalper\/produto\/armadilha-para-moscas-arandela-plus-personalize-a-sua-armadilha\/"},"modified":"2025-12-08T16:23:12","modified_gmt":"2025-12-08T19:23:12","slug":"armadilha-para-moscas-arandela-style-plus-personalizavel","status":"publish","type":"product","link":"https:\/\/embrevenoar.com.br\/dalper\/produto\/armadilha-para-moscas-arandela-style-plus-personalizavel\/","title":{"rendered":"Armadilha para Moscas Arandela Style Plus Personaliz\u00e1vel"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"30236\" class=\"elementor elementor-30236\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-32e5964 e-flex e-con-boxed e-con e-parent\" data-id=\"32e5964\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d55fc5d e-con-full e-flex e-con e-child\" data-id=\"d55fc5d\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cee899 elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"2cee899\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">O QUE VOC\u00ca EST\u00c1 COMPRANDO:<\/h3><p class=\"elementor-image-box-description\">Uma Armadilha Luminosa para Moscas PLUS Dalper - BIVOLT 127\/220\nO equipamento possui uma l\u00e2mpada fluorescente UV-A de 15watts e acompanha um refil adesivo grande (45cm x 22 cm)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0dd0e5 elementor-widget elementor-widget-image-box\" data-id=\"d0dd0e5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Garantia<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f1db56 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4f1db56\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Armadilha: 12 meses<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L\u00e2mpada: 03 meses<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Suporte t\u00e9cnico Dalper: permanente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a7e01e e-con-full e-flex e-con e-child\" data-id=\"6a7e01e\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-348f962 elementor-widget__width-inherit scroll-bottom elementor-widget-laptop__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-n-accordion\" data-id=\"348f962\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5510\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5510\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 1. FUNCIONAMENTO: <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"huge huge-arrow-up-02-round\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"huge huge-arrow-down-02-round\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5510\" class=\"elementor-element elementor-element-5ddfe00 e-con-full e-flex e-con e-child\" data-id=\"5ddfe00\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2149b09 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"2149b09\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A armadilha para moscas PLUS Dalper tem como finalidade o controle de insetos voadores no ambiente. Sua l\u00e2mpada UV-A atrai os insetos voadores (moscas, varejeiras, besouros, mariposas&#8230;). Os insetos atra\u00eddos entram na armadilha e s\u00e3o capturados em um refil adesivo, onde morrem grudados, sem que o ambiente seja contaminado por part\u00edculas do inseto. O refil adesivo \u00e9 descart\u00e1vel e de f\u00e1cil reposi\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5511\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5511\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2. MANUTEN\u00c7\u00c3O: <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"huge huge-arrow-up-02-round\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"huge huge-arrow-down-02-round\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5511\" class=\"elementor-element elementor-element-e6a9873 e-con-full e-flex e-con e-child\" data-id=\"e6a9873\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce07a41 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"ce07a41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De f\u00e1cil manuten\u00e7\u00e3o, a PLUS Dalper requer que o refil seja trocado conforme a infesta\u00e7\u00e3o de insetos voadores do local. Normalmente a cada 30\u00a0dias ou quando a superf\u00edcie do refil estiver com 70% da \u00e1rea coberta por insetos. A l\u00e2mpada tem uma vida \u00fatil de 10 meses, quando deve ser trocada mesmo sem estar queimada, devido a diminui\u00e7\u00e3o da capacidade de atra\u00e7\u00e3o dos insetos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5512\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5512\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 3. INDICA\u00c7\u00d5ES: <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"huge huge-arrow-up-02-round\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"huge huge-arrow-down-02-round\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5512\" class=\"elementor-element elementor-element-62f38a9 e-con-full e-flex e-con e-child\" data-id=\"62f38a9\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d0dfd6 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"1d0dfd6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Indicado para qualquer ambiente onde a presen\u00e7a de insetos causa desconforto ou risco \u00e0\u00a0sa\u00fade com a contamina\u00e7\u00e3o de produtos e\/ou alimentos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5513\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5513\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 4. INSTALA\u00c7\u00c3O: <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"huge huge-arrow-up-02-round\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"huge huge-arrow-down-02-round\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5513\" class=\"elementor-element elementor-element-637ccc3 e-con-full e-flex e-con e-child\" data-id=\"637ccc3\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d6148e color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"0d6148e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Instale sua Armadilha para moscas a uma altura de aproximadamente 1,80m do ch\u00e3o. Atente-se para n\u00e3o instalar o equipamento em frente de janelas e portas para n\u00e3o atrair insetos que estejam fora do ambiente. Uma dist\u00e2ncia de 3 metros de locais de manipula\u00e7\u00e3o de alimentos e outras fontes de luz auxiliam em um melhor funcionamento da armadilha.<\/p><p>A Armadilha para Moscas Arandela PLUS foi desenvolvida para utiliza\u00e7\u00e3o em ambientes cobertos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5514\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5514\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 5. TIPOS DE INSETOS ATRA\u00cdDOS: <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"huge huge-arrow-up-02-round\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"huge huge-arrow-down-02-round\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5514\" class=\"elementor-element elementor-element-08f82cc e-con-full e-flex e-con e-child\" data-id=\"08f82cc\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6df03a color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"d6df03a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Insetos voadores fotossens\u00edveis: moscas (dom\u00e9stica, varejeira, da fruta), mariposas, besouros, tra\u00e7as dos gr\u00e3os, enfim, todos os insetos fotossens\u00edveis, ou seja, que s\u00e3o atra\u00eddos por uma fonte de luz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5515\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5515\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 6. RECOMENDA\u00c7\u00d5ES DE USO: <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"huge huge-arrow-up-02-round\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"huge huge-arrow-down-02-round\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5515\" class=\"elementor-element elementor-element-46a7493 e-con-full e-flex e-con e-child\" data-id=\"46a7493\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-052de92 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"052de92\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Troque o refil a cada 30\u00a0dias aproximadamente.<br \/>Mantenha sua PLUS ligada durante 24h por dia para um melhor controle.<br \/>A l\u00e2mpada t\u00eam uma vida \u00fatil de 12 meses, quando deve ser trocada mesmo sem estar queimada, devido a diminui\u00e7\u00e3o da capacidade de atra\u00e7\u00e3o dos insetos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5516\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5516\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 7. ESPECIFICA\u00c7\u00d5ES T\u00c9CNICAS: <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"huge huge-arrow-up-02-round\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"huge huge-arrow-down-02-round\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5516\" class=\"elementor-element elementor-element-bc95e9f e-con-full e-flex e-con e-child\" data-id=\"bc95e9f\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed1eb4 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"1ed1eb4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Toda confeccionada em a\u00e7o com pintura ep\u00f3xi que resulta em uma maior durabilidade em rela\u00e7\u00e3o a outros equipamentos do mercado, facilitando tamb\u00e9m na limpeza do equipamento.<\/p><p>Dimens\u00f5es da armadilha: 57 cm x 18\u00a0cm x 15 cm<br \/>Possui 1 l\u00e2mpada UV-A de 15W<br \/>Refil adesivo grande: 45cm x 22cm<br \/>\u00c1rea de atua\u00e7\u00e3o: at\u00e9 25 m\u00b2<br \/>Bivolt: 127\/220V<\/p><p>Dispon\u00edvel nas cores BRANCA, PRETA ou A\u00c7O escovado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Armadilha para Moscas Arandela Plus, com alcance de at\u00e9 25m\u00b2, ideal para ambientes cobertos.<\/p>\n","protected":false},"featured_media":30238,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[88],"product_cat":[90,101,128],"product_tag":[],"class_list":["post-30236","product","type-product","status-publish","has-post-thumbnail","product_brand-dalper","product_cat-arandela","product_cat-arandela-1","product_cat-modelo-horizontal","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/product\/30236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/comments?post=30236"}],"version-history":[{"count":9,"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/product\/30236\/revisions"}],"predecessor-version":[{"id":31590,"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/product\/30236\/revisions\/31590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/media\/30238"}],"wp:attachment":[{"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/media?parent=30236"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/product_brand?post=30236"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/product_cat?post=30236"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/embrevenoar.com.br\/dalper\/wp-json\/wp\/v2\/product_tag?post=30236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}