{"id":11,"count":1,"description":"","link":"https:\/\/embrevenoar.com.br\/tempo\/category\/transfer\/","name":"Transfer","slug":"transfer","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/embrevenoar.com.br\/tempo\/wp-json\/wp\/v2\/categories\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/embrevenoar.com.br\/tempo\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/embrevenoar.com.br\/tempo\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/embrevenoar.com.br\/tempo\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}